{"id":1593,"date":"2021-12-02T19:07:48","date_gmt":"2021-12-02T11:07:48","guid":{"rendered":"http:\/\/icrazy-english.com.tw\/?post_type=course&#038;p=1593"},"modified":"2021-12-08T17:25:48","modified_gmt":"2021-12-08T09:25:48","slug":"englishstory2","status":"publish","type":"course","link":"https:\/\/icrazy-english.com.tw\/en\/course\/englishstory2","title":{"rendered":"\u82f1\u8a9e\u7e6a\u672c-\u4e2d\u7d1a"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1593\" class=\"elementor elementor-1593\" data-elementor-post-type=\"course\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-333d6b09 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"333d6b09\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-479879d5\" data-id=\"479879d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-484dcf6 elementor-widget elementor-widget-spacer\" data-id=\"484dcf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d1d7ffe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d1d7ffe\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0cb10ba\" data-id=\"0cb10ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1344199 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1344199\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7b60f2c\" data-id=\"7b60f2c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8006863 elementor-widget elementor-widget-image\" data-id=\"8006863\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-1598\" alt=\"\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326-150x150.jpg 150w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326-300x300.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326-12x12.jpg 12w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326.jpg 395w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e351bb1\" data-id=\"e351bb1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36f250a elementor-widget elementor-widget-heading\" data-id=\"36f250a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u82f1\u8a9e\u7e6a\u672c~\u4e2d\u7d1a<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2251d3 elementor-widget elementor-widget-heading\" data-id=\"a2251d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 14px;text-align: center;white-space: normal\">Level 3~Level4<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cb46fd elementor-widget elementor-widget-heading\" data-id=\"9cb46fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><h2 class=\"elementor-heading-title elementor-size-default\" style=\"font-style: normal;white-space: normal\">\u672c\u8ab2\u7a0b\u4e3b\u65e8\u85c9\u7531\u82f1\u8a9e\u7e6a\u672c\u751f\u52d5\u7684\u8272\u5f69\uff0c\u5229\u7528\u8aaa\u6545\u4e8b\u7684\u65b9\u5f0f\uff0c\u5f15\u5c0e\u5b78\u751f\u53c3\u8207\u6545\u4e8b\u7684\u8a0e\u8ad6\uff0c\u9032\u800c\u9054\u6210\u958b\u53e3\u8aaa\u7684\u76ee\u7684\n\u3002\u517125\u500b\u55ae\u5143\uff0c\u6bcf\u500b\u55ae\u5143\u51713\u8ab2\uff0c\u5408\u8a08\u517175\u8ab2\u3002\u6bcf\u8ab225\u5206\u9418\u3002<br><\/h2><span style=\"white-space: normal\">\u3002<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-baa18dc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"baa18dc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0c8ea0c\" data-id=\"0c8ea0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2337cb2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2337cb2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9b5636f\" data-id=\"9b5636f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45c370c elementor-widget elementor-widget-heading\" data-id=\"45c370c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">English Story~Intermediate<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-688c583 elementor-widget elementor-widget-heading\" data-id=\"688c583\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u672c\u518a\u517125\u500b\u55ae\u5143\uff0c\u6bcf\u500b\u55ae\u5143\u51713\u8ab2\uff0c\u6bcf\u55ae\u5143\u670920~30\u9801\u5167\u5bb9\u5408\u8a08\uff0c\u517175\u8ab2\u3002\u6bcf\u8ab225\u5206\u9418\u3002<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-e39301f elementor-widget elementor-widget-toggle\" data-id=\"e39301f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2381\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2381\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 01 A Zebra Called Dottie (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2381\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2381\"><h4><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-1598\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326-300x300.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326-150x150.jpg 150w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326-12x12.jpg 12w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326.jpg 395w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1iSBGd_9ttn8xEbLxU3SKb84ZnBcgnv7r\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2382\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2382\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 02 A Zebra Called Dottie (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2382\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2382\"><h4><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-1598\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326-300x300.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326-150x150.jpg 150w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326-12x12.jpg 12w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326.jpg 395w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1iSBGd_9ttn8xEbLxU3SKb84ZnBcgnv7r\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2383\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2383\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 03 A Zebra Called Dottie (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2383\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2383\"><h4><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-1598\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326-300x300.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326-150x150.jpg 150w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326-12x12.jpg 12w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326.jpg 395w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1iSBGd_9ttn8xEbLxU3SKb84ZnBcgnv7r\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2384\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2384\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 04 Alfi Blows Bubbles (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2384\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2384\"><h4>\u00a0<\/h4><p><img decoding=\"async\" class=\"alignnone size-medium wp-image-1602\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443602201-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443602201-300x168.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443602201-18x10.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443602201.jpg 690w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1tDYsRjB1PrKiZNg9MeyHLfqMQmdbYPPy\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2385\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2385\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 05 Alfi Blows Bubbles (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2385\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2385\"><h4>\u00a0<\/h4><p><img decoding=\"async\" class=\"alignnone size-medium wp-image-1602\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443602201-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443602201-300x168.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443602201-18x10.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443602201.jpg 690w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1tDYsRjB1PrKiZNg9MeyHLfqMQmdbYPPy\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2386\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2386\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 06 Alfi Blows Bubbles (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2386\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2386\"><h4>\u00a0<\/h4><p><img decoding=\"async\" class=\"alignnone size-medium wp-image-1602\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443602201-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443602201-300x168.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443602201-18x10.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443602201.jpg 690w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1tDYsRjB1PrKiZNg9MeyHLfqMQmdbYPPy\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2387\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-2387\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 07 Ann-Nem-Oh-Nee Finds Adventure (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2387\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-2387\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2388\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-2388\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 08 Ann-Nem-Oh-Nee Finds Adventure (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2388\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-2388\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2389\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-2389\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 09 Ann-Nem-Oh-Nee Finds Adventure (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2389\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-2389\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23810\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-23810\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 10 Bath time for Chunnu and Munnu (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23810\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-23810\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23811\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-23811\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 11 Bath time for Chunnu and Munnu (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23811\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-23811\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23812\" class=\"elementor-tab-title\" data-tab=\"12\" role=\"button\" aria-controls=\"elementor-tab-content-23812\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 12 Bath time for Chunnu and Munnu (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23812\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"12\" role=\"region\" aria-labelledby=\"elementor-tab-title-23812\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23813\" class=\"elementor-tab-title\" data-tab=\"13\" role=\"button\" aria-controls=\"elementor-tab-content-23813\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 13 Beatrix Potter Jemima Puddle Duck (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23813\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"13\" role=\"region\" aria-labelledby=\"elementor-tab-title-23813\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23814\" class=\"elementor-tab-title\" data-tab=\"14\" role=\"button\" aria-controls=\"elementor-tab-content-23814\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 14 Beatrix Potter Jemima Puddle Duck (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23814\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"14\" role=\"region\" aria-labelledby=\"elementor-tab-title-23814\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23815\" class=\"elementor-tab-title\" data-tab=\"15\" role=\"button\" aria-controls=\"elementor-tab-content-23815\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 15 Beatrix Potter Jemima Puddle Duck (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23815\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"15\" role=\"region\" aria-labelledby=\"elementor-tab-title-23815\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23816\" class=\"elementor-tab-title\" data-tab=\"16\" role=\"button\" aria-controls=\"elementor-tab-content-23816\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 16 Dipa karmakar in perfect balance (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23816\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"16\" role=\"region\" aria-labelledby=\"elementor-tab-title-23816\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23817\" class=\"elementor-tab-title\" data-tab=\"17\" role=\"button\" aria-controls=\"elementor-tab-content-23817\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 17 Dipa karmakar in perfect balance (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23817\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"17\" role=\"region\" aria-labelledby=\"elementor-tab-title-23817\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23818\" class=\"elementor-tab-title\" data-tab=\"18\" role=\"button\" aria-controls=\"elementor-tab-content-23818\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 18 Dipa karmakar in perfect balance (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23818\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"18\" role=\"region\" aria-labelledby=\"elementor-tab-title-23818\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23819\" class=\"elementor-tab-title\" data-tab=\"19\" role=\"button\" aria-controls=\"elementor-tab-content-23819\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 19 Gracas dream (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23819\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"19\" role=\"region\" aria-labelledby=\"elementor-tab-title-23819\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23820\" class=\"elementor-tab-title\" data-tab=\"20\" role=\"button\" aria-controls=\"elementor-tab-content-23820\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 20 Gracas dream (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23820\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"20\" role=\"region\" aria-labelledby=\"elementor-tab-title-23820\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23821\" class=\"elementor-tab-title\" data-tab=\"21\" role=\"button\" aria-controls=\"elementor-tab-content-23821\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 21 Gracas dream (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23821\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"21\" role=\"region\" aria-labelledby=\"elementor-tab-title-23821\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23822\" class=\"elementor-tab-title\" data-tab=\"22\" role=\"button\" aria-controls=\"elementor-tab-content-23822\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 22 Grandma's glasses (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23822\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"22\" role=\"region\" aria-labelledby=\"elementor-tab-title-23822\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23823\" class=\"elementor-tab-title\" data-tab=\"23\" role=\"button\" aria-controls=\"elementor-tab-content-23823\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 23 Grandma's glasses (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23823\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"23\" role=\"region\" aria-labelledby=\"elementor-tab-title-23823\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23824\" class=\"elementor-tab-title\" data-tab=\"24\" role=\"button\" aria-controls=\"elementor-tab-content-23824\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 24 Grandma's glasses (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23824\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"24\" role=\"region\" aria-labelledby=\"elementor-tab-title-23824\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23825\" class=\"elementor-tab-title\" data-tab=\"25\" role=\"button\" aria-controls=\"elementor-tab-content-23825\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 25 I Don't Want to go to Sleep (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23825\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"25\" role=\"region\" aria-labelledby=\"elementor-tab-title-23825\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23826\" class=\"elementor-tab-title\" data-tab=\"26\" role=\"button\" aria-controls=\"elementor-tab-content-23826\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 26 I Don't Want to go to Sleep (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23826\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"26\" role=\"region\" aria-labelledby=\"elementor-tab-title-23826\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23827\" class=\"elementor-tab-title\" data-tab=\"27\" role=\"button\" aria-controls=\"elementor-tab-content-23827\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 27 I Don't Want to go to Sleep (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23827\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"27\" role=\"region\" aria-labelledby=\"elementor-tab-title-23827\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23828\" class=\"elementor-tab-title\" data-tab=\"28\" role=\"button\" aria-controls=\"elementor-tab-content-23828\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 28 Is There Anyone Like Me (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23828\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"28\" role=\"region\" aria-labelledby=\"elementor-tab-title-23828\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23829\" class=\"elementor-tab-title\" data-tab=\"29\" role=\"button\" aria-controls=\"elementor-tab-content-23829\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 29 Is There Anyone Like Me (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23829\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"29\" role=\"region\" aria-labelledby=\"elementor-tab-title-23829\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23830\" class=\"elementor-tab-title\" data-tab=\"30\" role=\"button\" aria-controls=\"elementor-tab-content-23830\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 30 Is There Anyone Like Me (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23830\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"30\" role=\"region\" aria-labelledby=\"elementor-tab-title-23830\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23831\" class=\"elementor-tab-title\" data-tab=\"31\" role=\"button\" aria-controls=\"elementor-tab-content-23831\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 31 Little Goat (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23831\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"31\" role=\"region\" aria-labelledby=\"elementor-tab-title-23831\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23832\" class=\"elementor-tab-title\" data-tab=\"32\" role=\"button\" aria-controls=\"elementor-tab-content-23832\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 32 Little Goat (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23832\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"32\" role=\"region\" aria-labelledby=\"elementor-tab-title-23832\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23833\" class=\"elementor-tab-title\" data-tab=\"33\" role=\"button\" aria-controls=\"elementor-tab-content-23833\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 33 Little Goat (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23833\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"33\" role=\"region\" aria-labelledby=\"elementor-tab-title-23833\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23834\" class=\"elementor-tab-title\" data-tab=\"34\" role=\"button\" aria-controls=\"elementor-tab-content-23834\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 34 Lost and Found (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23834\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"34\" role=\"region\" aria-labelledby=\"elementor-tab-title-23834\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23835\" class=\"elementor-tab-title\" data-tab=\"35\" role=\"button\" aria-controls=\"elementor-tab-content-23835\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 35 Lost and Found (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23835\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"35\" role=\"region\" aria-labelledby=\"elementor-tab-title-23835\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23836\" class=\"elementor-tab-title\" data-tab=\"36\" role=\"button\" aria-controls=\"elementor-tab-content-23836\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 36 Lost and Found (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23836\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"36\" role=\"region\" aria-labelledby=\"elementor-tab-title-23836\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23837\" class=\"elementor-tab-title\" data-tab=\"37\" role=\"button\" aria-controls=\"elementor-tab-content-23837\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 37 Moo-moo-brown-cow-have-you-any-milk (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23837\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"37\" role=\"region\" aria-labelledby=\"elementor-tab-title-23837\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23838\" class=\"elementor-tab-title\" data-tab=\"38\" role=\"button\" aria-controls=\"elementor-tab-content-23838\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 38 Moo-moo-brown-cow-have-you-any-milk (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23838\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"38\" role=\"region\" aria-labelledby=\"elementor-tab-title-23838\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23839\" class=\"elementor-tab-title\" data-tab=\"39\" role=\"button\" aria-controls=\"elementor-tab-content-23839\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 39 Moo-moo-brown-cow-have-you-any-milk (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23839\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"39\" role=\"region\" aria-labelledby=\"elementor-tab-title-23839\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23840\" class=\"elementor-tab-title\" data-tab=\"40\" role=\"button\" aria-controls=\"elementor-tab-content-23840\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 40 More or less need to guess (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23840\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"40\" role=\"region\" aria-labelledby=\"elementor-tab-title-23840\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23841\" class=\"elementor-tab-title\" data-tab=\"41\" role=\"button\" aria-controls=\"elementor-tab-content-23841\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 41 More or less need to guess (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23841\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"41\" role=\"region\" aria-labelledby=\"elementor-tab-title-23841\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23842\" class=\"elementor-tab-title\" data-tab=\"42\" role=\"button\" aria-controls=\"elementor-tab-content-23842\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 42 More or less need to guess (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23842\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"42\" role=\"region\" aria-labelledby=\"elementor-tab-title-23842\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23843\" class=\"elementor-tab-title\" data-tab=\"43\" role=\"button\" aria-controls=\"elementor-tab-content-23843\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 43 My Dream In The Drawer (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23843\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"43\" role=\"region\" aria-labelledby=\"elementor-tab-title-23843\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23844\" class=\"elementor-tab-title\" data-tab=\"44\" role=\"button\" aria-controls=\"elementor-tab-content-23844\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 44 My Dream In The Drawer (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23844\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"44\" role=\"region\" aria-labelledby=\"elementor-tab-title-23844\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23845\" class=\"elementor-tab-title\" data-tab=\"45\" role=\"button\" aria-controls=\"elementor-tab-content-23845\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 45 My Dream In The Drawer (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23845\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"45\" role=\"region\" aria-labelledby=\"elementor-tab-title-23845\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23846\" class=\"elementor-tab-title\" data-tab=\"46\" role=\"button\" aria-controls=\"elementor-tab-content-23846\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 46 Pishi caught in a storm (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23846\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"46\" role=\"region\" aria-labelledby=\"elementor-tab-title-23846\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23847\" class=\"elementor-tab-title\" data-tab=\"47\" role=\"button\" aria-controls=\"elementor-tab-content-23847\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 47 Pishi caught in a storm (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23847\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"47\" role=\"region\" aria-labelledby=\"elementor-tab-title-23847\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23848\" class=\"elementor-tab-title\" data-tab=\"48\" role=\"button\" aria-controls=\"elementor-tab-content-23848\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 48 Pishi caught in a storm (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23848\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"48\" role=\"region\" aria-labelledby=\"elementor-tab-title-23848\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23849\" class=\"elementor-tab-title\" data-tab=\"49\" role=\"button\" aria-controls=\"elementor-tab-content-23849\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 49 Ritus letter gets longer (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23849\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"49\" role=\"region\" aria-labelledby=\"elementor-tab-title-23849\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23850\" class=\"elementor-tab-title\" data-tab=\"50\" role=\"button\" aria-controls=\"elementor-tab-content-23850\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 50 Ritus letter gets longer (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23850\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"50\" role=\"region\" aria-labelledby=\"elementor-tab-title-23850\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23851\" class=\"elementor-tab-title\" data-tab=\"51\" role=\"button\" aria-controls=\"elementor-tab-content-23851\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 51 Ritus letter gets longer (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23851\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"51\" role=\"region\" aria-labelledby=\"elementor-tab-title-23851\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23852\" class=\"elementor-tab-title\" data-tab=\"52\" role=\"button\" aria-controls=\"elementor-tab-content-23852\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 52 Save The Planet (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23852\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"52\" role=\"region\" aria-labelledby=\"elementor-tab-title-23852\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23853\" class=\"elementor-tab-title\" data-tab=\"53\" role=\"button\" aria-controls=\"elementor-tab-content-23853\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 53 Save The Planet (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23853\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"53\" role=\"region\" aria-labelledby=\"elementor-tab-title-23853\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23854\" class=\"elementor-tab-title\" data-tab=\"54\" role=\"button\" aria-controls=\"elementor-tab-content-23854\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 54 Save The Planet (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23854\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"54\" role=\"region\" aria-labelledby=\"elementor-tab-title-23854\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23855\" class=\"elementor-tab-title\" data-tab=\"55\" role=\"button\" aria-controls=\"elementor-tab-content-23855\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 55 Stick's Adventure (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23855\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"55\" role=\"region\" aria-labelledby=\"elementor-tab-title-23855\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23856\" class=\"elementor-tab-title\" data-tab=\"56\" role=\"button\" aria-controls=\"elementor-tab-content-23856\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 56 Stick's Adventure (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23856\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"56\" role=\"region\" aria-labelledby=\"elementor-tab-title-23856\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23857\" class=\"elementor-tab-title\" data-tab=\"57\" role=\"button\" aria-controls=\"elementor-tab-content-23857\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 57 Stick's Adventure (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23857\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"57\" role=\"region\" aria-labelledby=\"elementor-tab-title-23857\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23858\" class=\"elementor-tab-title\" data-tab=\"58\" role=\"button\" aria-controls=\"elementor-tab-content-23858\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 58 The Jealousy Germ (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23858\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"58\" role=\"region\" aria-labelledby=\"elementor-tab-title-23858\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23859\" class=\"elementor-tab-title\" data-tab=\"59\" role=\"button\" aria-controls=\"elementor-tab-content-23859\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 59 The Jealousy Germ (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23859\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"59\" role=\"region\" aria-labelledby=\"elementor-tab-title-23859\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23860\" class=\"elementor-tab-title\" data-tab=\"60\" role=\"button\" aria-controls=\"elementor-tab-content-23860\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 60 The Jealousy Germ (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23860\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"60\" role=\"region\" aria-labelledby=\"elementor-tab-title-23860\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23861\" class=\"elementor-tab-title\" data-tab=\"61\" role=\"button\" aria-controls=\"elementor-tab-content-23861\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 61 The little Tin Soldier (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23861\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"61\" role=\"region\" aria-labelledby=\"elementor-tab-title-23861\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23862\" class=\"elementor-tab-title\" data-tab=\"62\" role=\"button\" aria-controls=\"elementor-tab-content-23862\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 62 The little Tin Soldier (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23862\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"62\" role=\"region\" aria-labelledby=\"elementor-tab-title-23862\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23863\" class=\"elementor-tab-title\" data-tab=\"63\" role=\"button\" aria-controls=\"elementor-tab-content-23863\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 63 The little Tin Soldier (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23863\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"63\" role=\"region\" aria-labelledby=\"elementor-tab-title-23863\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23864\" class=\"elementor-tab-title\" data-tab=\"64\" role=\"button\" aria-controls=\"elementor-tab-content-23864\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 64 The Misadventures of the Little Toast (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23864\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"64\" role=\"region\" aria-labelledby=\"elementor-tab-title-23864\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23865\" class=\"elementor-tab-title\" data-tab=\"65\" role=\"button\" aria-controls=\"elementor-tab-content-23865\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 65 The Misadventures of the Little Toast (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23865\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"65\" role=\"region\" aria-labelledby=\"elementor-tab-title-23865\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23866\" class=\"elementor-tab-title\" data-tab=\"66\" role=\"button\" aria-controls=\"elementor-tab-content-23866\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 66 The Misadventures of the Little Toast (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23866\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"66\" role=\"region\" aria-labelledby=\"elementor-tab-title-23866\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23867\" class=\"elementor-tab-title\" data-tab=\"67\" role=\"button\" aria-controls=\"elementor-tab-content-23867\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 67 The Rabbit and the Flower (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23867\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"67\" role=\"region\" aria-labelledby=\"elementor-tab-title-23867\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23868\" class=\"elementor-tab-title\" data-tab=\"68\" role=\"button\" aria-controls=\"elementor-tab-content-23868\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 68 The Rabbit and the Flower (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23868\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"68\" role=\"region\" aria-labelledby=\"elementor-tab-title-23868\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23869\" class=\"elementor-tab-title\" data-tab=\"69\" role=\"button\" aria-controls=\"elementor-tab-content-23869\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 69 The Rabbit and the Flower (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23869\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"69\" role=\"region\" aria-labelledby=\"elementor-tab-title-23869\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23870\" class=\"elementor-tab-title\" data-tab=\"70\" role=\"button\" aria-controls=\"elementor-tab-content-23870\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 70 Who Stole Bhaiya Smile (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23870\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"70\" role=\"region\" aria-labelledby=\"elementor-tab-title-23870\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23871\" class=\"elementor-tab-title\" data-tab=\"71\" role=\"button\" aria-controls=\"elementor-tab-content-23871\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 71 Who Stole Bhaiya Smile (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23871\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"71\" role=\"region\" aria-labelledby=\"elementor-tab-title-23871\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23872\" class=\"elementor-tab-title\" data-tab=\"72\" role=\"button\" aria-controls=\"elementor-tab-content-23872\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 72 Who Stole Bhaiya Smile (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23872\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"72\" role=\"region\" aria-labelledby=\"elementor-tab-title-23872\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23873\" class=\"elementor-tab-title\" data-tab=\"73\" role=\"button\" aria-controls=\"elementor-tab-content-23873\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 73 Zandi and the Birdy Monster (1) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23873\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"73\" role=\"region\" aria-labelledby=\"elementor-tab-title-23873\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23874\" class=\"elementor-tab-title\" data-tab=\"74\" role=\"button\" aria-controls=\"elementor-tab-content-23874\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 74 Zandi and the Birdy Monster (2) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23874\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"74\" role=\"region\" aria-labelledby=\"elementor-tab-title-23874\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-23875\" class=\"elementor-tab-title\" data-tab=\"75\" role=\"button\" aria-controls=\"elementor-tab-content-23875\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u8ab2\u7a0b 75 Zandi and the Birdy Monster (3) <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23875\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"75\" role=\"region\" aria-labelledby=\"elementor-tab-title-23875\"><h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1607\" src=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-300x147.jpg 300w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658-18x9.jpg 18w, https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443833658.jpg 721w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h4><p>\u00a0<\/p><h4><a href=\"https:\/\/drive.google.com\/file\/d\/1RfeAtkTH_3JLdBGLxyVIHb_QWJwMTlZ0\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><u>\u9ede\u64ca\u770b\u6559\u6750<\/u><\/a><\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f480ddb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f480ddb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-892bff3\" data-id=\"892bff3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bd0f24 elementor-widget elementor-widget-spacer\" data-id=\"5bd0f24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"featured_media":1598,"template":"elementor_header_footer","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"course_tax":[22],"class_list":["post-1593","course","type-course","status-publish","has-post-thumbnail","hentry","course_tax-22"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u82f1\u8a9e\u7e6a\u672c-\u4e2d\u7d1a - iCrazy\u611b\u4e0a\u82f1\u6587\uff0d\u7dda\u4e0a1\u5c0d1\u5bb6\u6559\u5e73\u53f0<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/icrazy-english.com.tw\/en\/course\/englishstory2\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u82f1\u8a9e\u7e6a\u672c-\u4e2d\u7d1a - iCrazy\u611b\u4e0a\u82f1\u6587\uff0d\u7dda\u4e0a1\u5c0d1\u5bb6\u6559\u5e73\u53f0\" \/>\n<meta property=\"og:description\" content=\"\u82f1\u8a9e\u7e6a\u672c~\u4e2d\u7d1a Level 3~Level4 \u672c\u8ab2\u7a0b\u4e3b\u65e8\u85c9\u7531\u82f1\u8a9e\u7e6a\u672c\u751f\u52d5\u7684\u8272\u5f69\uff0c\u5229\u7528\u8aaa\u6545\u4e8b\u7684\u65b9\u5f0f\uff0c\u5f15\u5c0e\u5b78\u751f\u53c3\u8207 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/icrazy-english.com.tw\/en\/course\/englishstory2\" \/>\n<meta property=\"og:site_name\" content=\"iCrazy\u611b\u4e0a\u82f1\u6587\uff0d\u7dda\u4e0a1\u5c0d1\u5bb6\u6559\u5e73\u53f0\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-08T09:25:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"395\" \/>\n\t<meta property=\"og:image:height\" content=\"396\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/icrazy-english.com.tw\\\/en\\\/course\\\/englishstory2\",\"url\":\"http:\\\/\\\/icrazy-english.com.tw\\\/en\\\/course\\\/englishstory2\",\"name\":\"\u82f1\u8a9e\u7e6a\u672c-\u4e2d\u7d1a - iCrazy\u611b\u4e0a\u82f1\u6587\uff0d\u7dda\u4e0a1\u5c0d1\u5bb6\u6559\u5e73\u53f0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/icrazy-english.com.tw\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/icrazy-english.com.tw\\\/en\\\/course\\\/englishstory2#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/icrazy-english.com.tw\\\/en\\\/course\\\/englishstory2#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/icrazy-english.com.tw\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/1638443456326.jpg\",\"datePublished\":\"2021-12-02T11:07:48+00:00\",\"dateModified\":\"2021-12-08T09:25:48+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/icrazy-english.com.tw\\\/en\\\/course\\\/englishstory2#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/icrazy-english.com.tw\\\/en\\\/course\\\/englishstory2\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/icrazy-english.com.tw\\\/en\\\/course\\\/englishstory2#primaryimage\",\"url\":\"https:\\\/\\\/icrazy-english.com.tw\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/1638443456326.jpg\",\"contentUrl\":\"https:\\\/\\\/icrazy-english.com.tw\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/1638443456326.jpg\",\"width\":395,\"height\":396},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/icrazy-english.com.tw\\\/en\\\/course\\\/englishstory2#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9801\",\"item\":\"https:\\\/\\\/icrazy-english.com.tw\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u82f1\u8a9e\u7e6a\u672c-\u4e2d\u7d1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/icrazy-english.com.tw\\\/#website\",\"url\":\"https:\\\/\\\/icrazy-english.com.tw\\\/\",\"name\":\"iCrazy\u611b\u4e0a\u82f1\u6587\uff0d\u7dda\u4e0a1\u5c0d1\u5bb6\u6559\u5e73\u53f0\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/icrazy-english.com.tw\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/icrazy-english.com.tw\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/icrazy-english.com.tw\\\/#organization\",\"name\":\"iCrazy\u611b\u4e0a\u82f1\u6587\uff0d\u7dda\u4e0a1\u5c0d1\u5bb6\u6559\u5e73\u53f0\",\"url\":\"https:\\\/\\\/icrazy-english.com.tw\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/icrazy-english.com.tw\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/icrazy-english.com.tw\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cropped-icrazyschool-logo.png\",\"contentUrl\":\"https:\\\/\\\/icrazy-english.com.tw\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cropped-icrazyschool-logo.png\",\"width\":512,\"height\":512,\"caption\":\"iCrazy\u611b\u4e0a\u82f1\u6587\uff0d\u7dda\u4e0a1\u5c0d1\u5bb6\u6559\u5e73\u53f0\"},\"image\":{\"@id\":\"https:\\\/\\\/icrazy-english.com.tw\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u82f1\u8a9e\u7e6a\u672c-\u4e2d\u7d1a - iCrazy\u611b\u4e0a\u82f1\u6587\uff0d\u7dda\u4e0a1\u5c0d1\u5bb6\u6559\u5e73\u53f0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/icrazy-english.com.tw\/en\/course\/englishstory2","og_locale":"en_US","og_type":"article","og_title":"\u82f1\u8a9e\u7e6a\u672c-\u4e2d\u7d1a - iCrazy\u611b\u4e0a\u82f1\u6587\uff0d\u7dda\u4e0a1\u5c0d1\u5bb6\u6559\u5e73\u53f0","og_description":"\u82f1\u8a9e\u7e6a\u672c~\u4e2d\u7d1a Level 3~Level4 \u672c\u8ab2\u7a0b\u4e3b\u65e8\u85c9\u7531\u82f1\u8a9e\u7e6a\u672c\u751f\u52d5\u7684\u8272\u5f69\uff0c\u5229\u7528\u8aaa\u6545\u4e8b\u7684\u65b9\u5f0f\uff0c\u5f15\u5c0e\u5b78\u751f\u53c3\u8207 [&hellip;]","og_url":"http:\/\/icrazy-english.com.tw\/en\/course\/englishstory2","og_site_name":"iCrazy\u611b\u4e0a\u82f1\u6587\uff0d\u7dda\u4e0a1\u5c0d1\u5bb6\u6559\u5e73\u53f0","article_modified_time":"2021-12-08T09:25:48+00:00","og_image":[{"width":395,"height":396,"url":"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/icrazy-english.com.tw\/en\/course\/englishstory2","url":"http:\/\/icrazy-english.com.tw\/en\/course\/englishstory2","name":"\u82f1\u8a9e\u7e6a\u672c-\u4e2d\u7d1a - iCrazy\u611b\u4e0a\u82f1\u6587\uff0d\u7dda\u4e0a1\u5c0d1\u5bb6\u6559\u5e73\u53f0","isPartOf":{"@id":"https:\/\/icrazy-english.com.tw\/#website"},"primaryImageOfPage":{"@id":"http:\/\/icrazy-english.com.tw\/en\/course\/englishstory2#primaryimage"},"image":{"@id":"http:\/\/icrazy-english.com.tw\/en\/course\/englishstory2#primaryimage"},"thumbnailUrl":"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326.jpg","datePublished":"2021-12-02T11:07:48+00:00","dateModified":"2021-12-08T09:25:48+00:00","breadcrumb":{"@id":"http:\/\/icrazy-english.com.tw\/en\/course\/englishstory2#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/icrazy-english.com.tw\/en\/course\/englishstory2"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/icrazy-english.com.tw\/en\/course\/englishstory2#primaryimage","url":"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326.jpg","contentUrl":"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/12\/1638443456326.jpg","width":395,"height":396},{"@type":"BreadcrumbList","@id":"http:\/\/icrazy-english.com.tw\/en\/course\/englishstory2#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9801","item":"https:\/\/icrazy-english.com.tw\/"},{"@type":"ListItem","position":2,"name":"\u82f1\u8a9e\u7e6a\u672c-\u4e2d\u7d1a"}]},{"@type":"WebSite","@id":"https:\/\/icrazy-english.com.tw\/#website","url":"https:\/\/icrazy-english.com.tw\/","name":"iCrazy\u611b\u4e0a\u82f1\u6587\uff0d\u7dda\u4e0a1\u5c0d1\u5bb6\u6559\u5e73\u53f0","description":"","publisher":{"@id":"https:\/\/icrazy-english.com.tw\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/icrazy-english.com.tw\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/icrazy-english.com.tw\/#organization","name":"iCrazy\u611b\u4e0a\u82f1\u6587\uff0d\u7dda\u4e0a1\u5c0d1\u5bb6\u6559\u5e73\u53f0","url":"https:\/\/icrazy-english.com.tw\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/icrazy-english.com.tw\/#\/schema\/logo\/image\/","url":"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/09\/cropped-icrazyschool-logo.png","contentUrl":"https:\/\/icrazy-english.com.tw\/wp-content\/uploads\/2021\/09\/cropped-icrazyschool-logo.png","width":512,"height":512,"caption":"iCrazy\u611b\u4e0a\u82f1\u6587\uff0d\u7dda\u4e0a1\u5c0d1\u5bb6\u6559\u5e73\u53f0"},"image":{"@id":"https:\/\/icrazy-english.com.tw\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/icrazy-english.com.tw\/en\/wp-json\/wp\/v2\/course\/1593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/icrazy-english.com.tw\/en\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/icrazy-english.com.tw\/en\/wp-json\/wp\/v2\/types\/course"}],"version-history":[{"count":38,"href":"https:\/\/icrazy-english.com.tw\/en\/wp-json\/wp\/v2\/course\/1593\/revisions"}],"predecessor-version":[{"id":1642,"href":"https:\/\/icrazy-english.com.tw\/en\/wp-json\/wp\/v2\/course\/1593\/revisions\/1642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/icrazy-english.com.tw\/en\/wp-json\/wp\/v2\/media\/1598"}],"wp:attachment":[{"href":"https:\/\/icrazy-english.com.tw\/en\/wp-json\/wp\/v2\/media?parent=1593"}],"wp:term":[{"taxonomy":"course_tax","embeddable":true,"href":"https:\/\/icrazy-english.com.tw\/en\/wp-json\/wp\/v2\/course_tax?post=1593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}